{"id":7137,"date":"2024-08-26T14:34:17","date_gmt":"2024-08-26T14:34:17","guid":{"rendered":"https:\/\/krankenhauspfarramt.de\/index.php\/2024\/08\/26\/militaerische-gewalt-wird-den-konflikt-nicht-loesen-ekd\/"},"modified":"2024-08-26T14:34:20","modified_gmt":"2024-08-26T14:34:20","slug":"militaerische-gewalt-wird-den-konflikt-nicht-loesen-ekd","status":"publish","type":"post","link":"https:\/\/krankenhauspfarramt.de\/index.php\/2024\/08\/26\/militaerische-gewalt-wird-den-konflikt-nicht-loesen-ekd\/","title":{"rendered":"Milit\u00e4rische Gewalt wird den Konflikt nicht l\u00f6sen \u2013 EKD"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><em>Was h\u00f6ren Sie von Ihren Partnern \u00fcber die Situation in Gaza?<\/em><\/p>\n<p>Die Berichte aus Gaza sind schockierend. Das Leid dort ist kaum zu beschreiben, und die Rechtlosigkeit ist tiefgreifend. In Gespr\u00e4chen mit \u00c4rzten in Gaza haben wir beschrieben bekommen, wie Kinder massiv unterern\u00e4hrt sind, wie M\u00fctter ihre Babys nicht ausreichend ern\u00e4hren k\u00f6nnen. Ein Kinderarzt eines christlichen Krankenhauses erz\u00e4hlte von einem der letzten Tage, an dem er 310 Kinder untersucht hat, 105 davon waren unterern\u00e4hrt. Viele \u00c4rzte leben selbst in Zelten und wechseln ihren Standort, je nachdem, wo die israelische Armee gerade Bombardierungen ank\u00fcndigt. Eine andere Person hat in einem Gespr\u00e4ch sehr bitter gesagt: \u201eWir wollen auch keine Gebete mehr, wenn kein Handeln folgt, wenn niemand verhindert, was hier passiert.\u201c<\/p>\n<p>Die Drastik und emotionale Wucht in den Berichten ersch\u00fcttern mich. Bei den Familien der Geiseln auf der israelischen Seite ist ebenfalls nur Verzweiflung. Deswegen fordern wir als Weltkirchenrat dringend einen Waffenstillstand und eine Freilassung aller Geiseln, um diesen Wahnsinn zu stoppen.<\/p>\n<p><em>Wie bewerten Sie die aktuelle Eskalation?<\/em><\/p>\n<p>Die massiven Bombardements in Gaza sind aus meiner Sicht durch nichts mehr zu rechtfertigen, auch nicht durch das Recht auf Selbstverteidigung. Der terroristische \u00dcberfall der Hamas am 7. Oktober war grausam und in jeder Hinsicht inakzeptabel, aber Israels milit\u00e4rische Gegenreaktion hat jede Verh\u00e4ltnism\u00e4\u00dfigkeit hinter sich gelassen. Das Leid, das dadurch verursacht wird, schreit zum Himmel. Ich halte es f\u00fcr eine ganz wichtige Aufgabe des Weltkirchenrats, das Leid auf beiden Seiten sichtbar zu machen.<\/p>\n<p>Empathie bew\u00e4hrt sich dann, wenn sie nicht nur denjenigen gilt, bei denen sie spontan da ist, sondern auch denjenigen, die auf der anderen Seite stehen. Die 102-j\u00e4hrige Holocaust-\u00dcberlebende Margot Friedl\u00e4nder hat k\u00fcrzlich gesagt: \u201eEs gibt kein christliches, kein arabisches, kein j\u00fcdisches Blut. Es gibt nur menschliches Blut.\u201c Dieser eindrucksvolle Satz gilt auch f\u00fcr menschliches Leid. Dass wir uns gerade in Deutschland den Nachfahren der Menschen, die im Holocaust ermordet wurden, besonders nahe f\u00fchlen, kann uns nicht davon abhalten, gegen die Gewalt und das Unrecht zu protestieren, das Pal\u00e4stinensern im Gaza-Streifen und auf der Westbank angetan wird.<\/p>\n<p><em>Man wagt es kaum zu fragen, aber haben Sie eine Perspektive f\u00fcr eine L\u00f6sung?<\/em><\/p>\n<p>Der erste Schritt muss ein sofortiger Waffenstillstand sein, um die humanit\u00e4re Versorgung in Gaza zu sichern und die israelischen Geiseln freizubekommen. Die internationale Gemeinschaft muss ihren Druck hier verst\u00e4rken. Langfristig ist eine Zwei-Staaten-L\u00f6sung f\u00fcr mich der einzige gangbare Weg. Das pal\u00e4stinensische Volk bek\u00e4me einen eigenen Staat, und die Rechte aller w\u00fcrden respektiert. Ein gerechter Frieden, der auf internationalem Recht basiert, ist der Schl\u00fcssel f\u00fcr eine sichere Zukunft beider V\u00f6lker.<\/p>\n<p><em>Wie realistisch ist dieser Traum in der aktuellen Situation?<\/em><\/p>\n<p>Im Moment scheint dieser Traum noch fern. Man muss ja die Frage stellen, wohin der Krieg f\u00fchren soll. Und die Antwort ist aus meiner Sicht: Seine Fortsetzung f\u00fchrt nur zu einem andauernden Blutbad. Der einzige Weg zu einer langfristigen Sicherheit, die ich mir f\u00fcr die Menschen in Israel genauso sehr w\u00fcnsche wie f\u00fcr die in Pal\u00e4stina, ist ein gerechter Frieden, der den Hass auf beiden Seiten \u00fcberwindet. Dass die brutalen Morde der Hamas-K\u00e4mpfer am 7. Oktober auf pal\u00e4stinensischer Seite nur noch mehr Leid verursacht haben, sehen wir jetzt. Wenn man umgekehrt auf israelischer Seite allein auf milit\u00e4rische Gewalt setzt, wird man immer neue Hamas-K\u00e4mpfer produzieren. Die Gewaltspirale geht immer weiter. Damit muss endlich Schluss sein!<\/p>\n<p style=\"text-align:right\"><em>epd-Gespr\u00e4ch: Franziska Hein<\/em><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Was h\u00f6ren Sie von Ihren Partnern \u00fcber die Situation in Gaza? Die Berichte aus Gaza sind schockierend. Das Leid dort<\/p>\n","protected":false},"author":2,"featured_media":7138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts\/7137"}],"collection":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/comments?post=7137"}],"version-history":[{"count":1,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts\/7137\/revisions"}],"predecessor-version":[{"id":7139,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts\/7137\/revisions\/7139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/media\/7138"}],"wp:attachment":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/media?parent=7137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/categories?post=7137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/tags?post=7137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}