{"id":9269,"date":"2026-05-13T13:26:54","date_gmt":"2026-05-13T13:26:54","guid":{"rendered":"https:\/\/krankenhauspfarramt.de\/index.php\/2026\/05\/13\/dieser-kuester-zeigt-seinen-alltag-auf-youtube-ekd\/"},"modified":"2026-05-13T13:26:56","modified_gmt":"2026-05-13T13:26:56","slug":"dieser-kuester-zeigt-seinen-alltag-auf-youtube-ekd","status":"publish","type":"post","link":"https:\/\/krankenhauspfarramt.de\/index.php\/2026\/05\/13\/dieser-kuester-zeigt-seinen-alltag-auf-youtube-ekd\/","title":{"rendered":"Dieser K\u00fcster zeigt seinen Alltag auf YouTube \u2013 EKD"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<h3>Warum der Job als K\u00fcster nie langweilig wird<\/h3>\n<p>Dass der K\u00fcsterberuf kreativ sein kann, \u00fcberrascht ihn bis heute. Mal h\u00e4ngt er die Lieder f\u00fcr den Sonntagsgottesdienst aus, mal spielt er mit seiner Band bei Gemeindeveranstaltungen Musik. Und manchmal darf er bei Festen auch einfach \u201eden Kasper machen\u201c, wie er sagt.<\/p>\n<p>In der Gemeinde sei immer etwas los. Die Pastoren seien besonders engagiert, st\u00e4ndig gebe es neue Projekte, Aktionen oder Ideen \u2013 sogar eine Schaukel in der Kirche. Auch die Gottesdienste seien gut besucht. \u201eBei uns ist richtig was los\u201c, sagt Ulli Walz stolz.<\/p>\n<p>Dass er mit Mitte f\u00fcnfzig noch einmal ganz neu angefangen hat, empfindet er heute als Gl\u00fccksfall. \u201eEs war absolut die richtige Entscheidung\u201c, sagt er. \u201eMontagmorgen? Kein Problem.\u201c<\/p>\n<h3>Wertsch\u00e4tzung als K\u00fcster in der Gemeinde<\/h3>\n<p>Statt Fehlersuche an Autos stehen heute Menschen im Mittelpunkt. \u201eEs ist auch Stress, aber ein anderer Stress, ein anderer Vibe\u201c, sagt Ulli Walz. Die Kommunikation und der Umgang miteinander seien ganz anders als in der Werkstatt.<\/p>\n<p>Besonders sch\u00e4tzt er die Gemeinschaft. Inzwischen f\u00fchlt er sich fest in der Gemeinde verankert. \u201eIch bin tief im Kaninchenbau\u201c, sagt er lachend. \u201eIch bekomme viel Wertsch\u00e4tzung und Anerkennung.\u201c<\/p>\n<p>Auch wenn einmal Probleme auftauchten, k\u00f6nne er diese offen ansprechen und bekomme Unterst\u00fctzung. Dieses Miteinander sei etwas Besonderes.<\/p>\n<p>Und noch etwas bewegt ihn: die spirituelle Seite seiner Arbeit. Beim Abendmahl Brot auszuteilen, h\u00e4tte er sich fr\u00fcher nie vorstellen k\u00f6nnen. \u201eIch h\u00e4tte nie gedacht, dass ich so etwas mal machen darf\u201c, sagt er. \u201eDiesen Teil m\u00f6chte ich nicht missen.\u201c<\/p>\n<p style=\"text-align:right\"><em>Text: Franziska Wei\u00df<\/em><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Warum der Job als K\u00fcster nie langweilig wird Dass der K\u00fcsterberuf kreativ sein kann, \u00fcberrascht ihn bis heute. Mal h\u00e4ngt<\/p>\n","protected":false},"author":2,"featured_media":9270,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts\/9269"}],"collection":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/comments?post=9269"}],"version-history":[{"count":1,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts\/9269\/revisions"}],"predecessor-version":[{"id":9271,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/posts\/9269\/revisions\/9271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/media\/9270"}],"wp:attachment":[{"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/media?parent=9269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/categories?post=9269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/krankenhauspfarramt.de\/index.php\/wp-json\/wp\/v2\/tags?post=9269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}